{"id":290,"date":"2024-03-26T21:02:28","date_gmt":"2024-03-27T03:02:28","guid":{"rendered":"https:\/\/jovial-yalow.104-219-41-121.plesk.page\/?p=290"},"modified":"2024-05-18T15:42:51","modified_gmt":"2024-05-18T21:42:51","slug":"inicia-taller-constitucion-de-asociaciones-civiles-2","status":"publish","type":"post","link":"https:\/\/monitorvecinal.org\/index.php\/blog\/eventos\/inicia-taller-constitucion-de-asociaciones-civiles-2\/","title":{"rendered":"Inicia Taller &#8220;Constituci\u00f3n de Asociaciones Civiles&#8221;"},"content":{"rendered":"\n<p><em><em>\u00bfC\u00f3mo celebrar una Asamblea?<\/em><\/em><\/p>\n\n\n\n<p><em>\u00bfQu\u00e9 hacer con los morosos?<\/em><\/p>\n\n\n\n<p><em>\u00bfQu\u00e9 l\u00edmites y obligaciones tiene el desarrollador?<\/em><\/p>\n\n\n\n<p><em>\u00bfQu\u00e9 responsabilidades adquiero al comprar en r\u00e9gimen condominal?<\/em><\/p>\n\n\n\n<p><strong>Para aclarar \u00e9stas y muchas inquietudes m\u00e1s, la Red Ciudadana de la Colonia Zibat\u00e1 promovi\u00f3 el taller \u201cConstituci\u00f3n de Asociaciones Civiles\u201d, con el fin de sumar a la construcci\u00f3n de una comunidad responsable basada en legalidad y conocimiento.<\/strong><\/p>\n\n\n\n<p>Bajo el auspicio y organizaci\u00f3n de la Red Ciudadana de la Colonia Zibat\u00e1, el pasado lunes 24 de febrero, a las&nbsp;19:00 horas, inici\u00f3 en las instalaciones comunitarias del Conjunto Artessa de Zibat\u00e1, el Taller denominado&nbsp;\u201cConstituci\u00f3n de Asociaciones Civiles\u201d, impartido por la Lic. Paulina Aguilar, integrante del equipo parlamentario&nbsp;de la Lic. Mar\u00eda Alem\u00e1n Mu\u00f1oz, Diputada Federal por el Estado de Quer\u00e9taro y quien ha trabajado en la&nbsp;elaboraci\u00f3n de reformas al C\u00f3digo Urbano de la entidad en materia de organizaci\u00f3n condominal, desde junio de&nbsp;2016.<\/p>\n\n\n\n<p>Los temas que se abordaron de manera introductoria en esta primera sesi\u00f3n fueron, entre otros: la naturaleza&nbsp;del r\u00e9gimen de propiedad en condominio; los derechos y obligaciones de los cond\u00f3minos, as\u00ed como de los&nbsp;desarrolladores en su calidad de propietarios de viviendas no vendidas; la convocatoria de asambleas generales&nbsp;condominales; la operaci\u00f3n de los \u00f3rganos de gobierno en el r\u00e9gimen condominal; y, algunos aspectos del&nbsp;proceso de entrega-recepci\u00f3n a los municipios, considerando la responsabilidad del constructor en el&nbsp;afianzamiento de garant\u00edas.<\/p>\n\n\n\n<p>En la exposici\u00f3n se coment\u00f3 tambi\u00e9n sobre el alto porcentaje de propiedades en r\u00e9gimen condominal en uso&nbsp;habitacional, comercial, e incluso industrial existente en el Estado de Quer\u00e9taro -particularmente, en el&nbsp;municipio \u201cEl Marqu\u00e9s\u201d. Tambi\u00e9n se enfatiz\u00f3 el papel de las iniciativas efectuadas al C\u00f3digo: la firma de&nbsp;convenios para el ingreso de cuerpos de emergencia en los condominios; la facultaci\u00f3n de posibilidades de&nbsp;mediaci\u00f3n para dirimir conflictos condominales; la promoci\u00f3n de la cultura condominal en municipios; y la&nbsp;prestaci\u00f3n de servicios p\u00fablicos por parte del municipio al interior de los condominios.<\/p>\n\n\n\n<p>Igualmente, se revisaron algunos art\u00edculos del C\u00f3digo Urbano, como aqu\u00e9llos que facilitan la organizaci\u00f3n y&nbsp;administraci\u00f3n m\u00e1s eficiente de los condominios, al incluir reglas claras para la toma de las decisiones colectivas,&nbsp;reconociendo y delimit\u00e1ndose con precisi\u00f3n los derechos y las obligaciones de propietarios y residentes;&nbsp;aqu\u00e9llos que establecen mecanismos de transparencia y rendici\u00f3n de cuentas para los administradores; y&nbsp;aqu\u00e9llos que facilitan los procesos de entrega-recepci\u00f3n a los municipios.<\/p>\n\n\n\n<p>Al haberse abundado en asuntos espec\u00edficos de la cultura condominal, se puntualizaron aspectos que es&nbsp;importante conocer cuando se adquiere o se renta una propiedad dentro del r\u00e9gimen condominal, ya que hay&nbsp;mucho desconocimiento de parte de los compradores y arrendatarios respecto a los derechos y obligaciones&nbsp;que tambi\u00e9n se adquieren tanto en \u00e1reas privativas como comunes.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/monitorvecinal.org\/web\/image\/689\/20200224%20-%20Introduccion%20al%20taller%20de%20constitucion02.jpg?access_token=23b97714-bfbf-4667-a783-f135f38fb1da\" alt=\"Odoo \u2022 Texto e imagen\" title=\"\"\/><\/figure>\n\n\n\n<p>Los Presidentes y Representantes de las diversas privadas, asistentes a esta primera sesi\u00f3n, pudieron exponer&nbsp;algunas de sus problem\u00e1ticas relativas: a la celebraci\u00f3n de su primera asamblea condominal; a la constituci\u00f3n de&nbsp;las asociales civiles por parte de las constructoras; al papel de los desarrolladores en la constituci\u00f3n del r\u00e9gimen&nbsp;de propiedad en condominio; y al proceso legal contra deudores de cuotas de mantenimiento y su recuperaci\u00f3n,&nbsp;entre otros.<\/p>\n\n\n\n<p>Los asistentes a esta reuni\u00f3n introductoria continuar\u00e1n con las sesiones del curso, con la intenci\u00f3n de compartir\u00a0con sus vecinos de privada o condominio la informaci\u00f3n obtenida, y organizar de mejor manera a sus colectivos\u00a0vecinales.<\/p>\n\n\n\n<p class=\"has-x-small-font-size\"><em>Informaci\u00f3n publicada en febrero 2020.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el auspicio y organizaci\u00f3n de la Red Ciudadana de la Colonia Zibat\u00e1, inici\u00f3 el Taller \u201cConstituci\u00f3n de Asociaciones Civiles\u201d.<\/p>\n","protected":false},"author":1,"featured_media":292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"footnotes":""},"categories":[11],"tags":[14],"class_list":["post-290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-taller"],"_links":{"self":[{"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/posts\/290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/comments?post=290"}],"version-history":[{"count":3,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/posts\/290\/revisions"}],"predecessor-version":[{"id":544,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/posts\/290\/revisions\/544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/media\/292"}],"wp:attachment":[{"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/media?parent=290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/categories?post=290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/tags?post=290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}