{"id":1189,"date":"2025-02-13T19:28:15","date_gmt":"2025-02-14T01:28:15","guid":{"rendered":"https:\/\/redzibata.org\/?p=1189"},"modified":"2025-02-13T20:26:42","modified_gmt":"2025-02-14T02:26:42","slug":"brigada-anti-incendios-de-zibata","status":"publish","type":"post","link":"https:\/\/monitorvecinal.org\/index.php\/blog\/seguridad_ciudadana\/brigada-anti-incendios-de-zibata\/","title":{"rendered":"Brigada anti-incendios de Zibat\u00e1"},"content":{"rendered":"\n<p>\u00a1Atenci\u00f3n, vecinos de Zibat\u00e1!<br>La seguridad de nuestra comunidad es primordial, por ello, en estas temporadas de incendios, queremos informarles que en Zibat\u00e1 contamos con una brigada anti-incendios altamente capacitada, conformada por personal del equipo de seguridad, bi\u00f3logos y mantenimiento de Zibat\u00e1.<br>Ante cualquier conato de incendio, por peque\u00f1o que sea, o si detectan humo, no duden en actuar de inmediato:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reporten el incidente al Centro de Monitoreo y Seguridad de Zibat\u00e1 (442 227 1356). Ellos activar\u00e1n de inmediato a la brigada anti-incendios para que se desplacen al lugar y controlen la situaci\u00f3n.<\/li>\n\n\n\n<li>Simult\u00e1neamente, llamen al 911. Esto permitir\u00e1 que Protecci\u00f3n Civil se coordine con la brigada y brinde apoyo adicional en caso de ser necesario.<br><\/li>\n<\/ul>\n\n\n\n<p>Es importante destacar que esta brigada antiincendios actuar\u00e1 de manera oportuna mientras Protecci\u00f3n Civil llega al lugar.<\/p>\n\n\n\n<p>La prevenci\u00f3n y la respuesta oportuna son clave para evitar que un peque\u00f1o incidente se convierta en una emergencia mayor. \u00a1Juntos cuidamos de Zibat\u00e1!<\/p>\n\n\n\n<p><br>Atentamente,<br>Red Ciudadana Zibat\u00e1<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&iexcl;Atenci&oacute;n, vecinos de Zibat&aacute;!La seguridad de nuestra comunidad es primordial, por ello, en estas temporadas de incendios, queremos informarles que en Zibat&aacute; contamos con una brigada anti-incendios altamente capacitada, conformada [&hellip;]<\/p>\n","protected":false},"author":156,"featured_media":1191,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad_ciudadana"],"_links":{"self":[{"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/posts\/1189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/users\/156"}],"replies":[{"embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/comments?post=1189"}],"version-history":[{"count":2,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/posts\/1189\/revisions"}],"predecessor-version":[{"id":1192,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/posts\/1189\/revisions\/1192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/media\/1191"}],"wp:attachment":[{"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/media?parent=1189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/categories?post=1189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monitorvecinal.org\/index.php\/wp-json\/wp\/v2\/tags?post=1189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}